{"id":24952,"date":"2025-11-04T11:35:12","date_gmt":"2025-11-04T10:35:12","guid":{"rendered":"https:\/\/www.ocmflex.com\/salon-refrigera-2025\/"},"modified":"2025-11-12T16:57:45","modified_gmt":"2025-11-12T15:57:45","slug":"salon-refrigera-2025","status":"publish","type":"post","link":"https:\/\/www.ocmflex.com\/fr\/salon-refrigera-2025\/","title":{"rendered":"Salon Refrigera 2025"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"24952\" class=\"elementor elementor-24952 elementor-24917\" data-elementor-settings=\"{&quot;element_pack_global_tooltip_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_padding&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_padding_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_padding_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true}}\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e9d566f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e9d566f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-57b88a67\" data-id=\"57b88a67\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-64269afe elementor-widget elementor-widget-heading\" data-id=\"64269afe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">SALON REFRIGERA 2025<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-473016c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"473016c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3c03805\" data-id=\"3c03805\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d46fac3 elementor-widget elementor-widget-heading\" data-id=\"d46fac3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">5 - 7 novembre 2025 - rendez-vous au stand A35 o\u00f9 notre \u00e9quipe OCM sera pr\u00eate \u00e0 vous pr\u00e9senter toutes nos nouveaut\u00e9s.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d74d79f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d74d79f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-68d671c\" data-id=\"68d671c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6b8b4e8 elementor-widget elementor-widget-image\" data-id=\"6b8b4e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.ocmflex.com\/wp-content\/uploads\/2025\/11\/IMG_0292_A-1024x768.jpg\" class=\"attachment-large size-large wp-image-24939\" alt=\"FIERA REFRIGERA 2025\" srcset=\"https:\/\/www.ocmflex.com\/wp-content\/uploads\/2025\/11\/IMG_0292_A-1024x768.jpg 1024w, https:\/\/www.ocmflex.com\/wp-content\/uploads\/2025\/11\/IMG_0292_A-300x225.jpg 300w, https:\/\/www.ocmflex.com\/wp-content\/uploads\/2025\/11\/IMG_0292_A-768x576.jpg 768w, https:\/\/www.ocmflex.com\/wp-content\/uploads\/2025\/11\/IMG_0292_A-1536x1152.jpg 1536w, https:\/\/www.ocmflex.com\/wp-content\/uploads\/2025\/11\/IMG_0292_A-scaled.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-316b3ac\" data-id=\"316b3ac\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d79f33c elementor-widget elementor-widget-image\" data-id=\"d79f33c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/www.ocmflex.com\/wp-content\/uploads\/2025\/11\/REFRIGERA-2025-1024x576.png\" class=\"attachment-large size-large wp-image-24934\" alt=\"FIERA REFRIGERA 2025\" srcset=\"https:\/\/www.ocmflex.com\/wp-content\/uploads\/2025\/11\/REFRIGERA-2025-1024x576.png 1024w, https:\/\/www.ocmflex.com\/wp-content\/uploads\/2025\/11\/REFRIGERA-2025-300x169.png 300w, https:\/\/www.ocmflex.com\/wp-content\/uploads\/2025\/11\/REFRIGERA-2025-768x432.png 768w, https:\/\/www.ocmflex.com\/wp-content\/uploads\/2025\/11\/REFRIGERA-2025-1536x864.png 1536w, https:\/\/www.ocmflex.com\/wp-content\/uploads\/2025\/11\/REFRIGERA-2025-scaled.png 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-df86e84\" data-id=\"df86e84\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a42b179 elementor-widget elementor-widget-image\" data-id=\"a42b179\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.ocmflex.com\/wp-content\/uploads\/2025\/11\/IMG_9920_A-1024x768.jpg\" class=\"attachment-large size-large wp-image-24920\" alt=\"FIERA REFRIGERA 2025\" srcset=\"https:\/\/www.ocmflex.com\/wp-content\/uploads\/2025\/11\/IMG_9920_A-1024x768.jpg 1024w, https:\/\/www.ocmflex.com\/wp-content\/uploads\/2025\/11\/IMG_9920_A-300x225.jpg 300w, https:\/\/www.ocmflex.com\/wp-content\/uploads\/2025\/11\/IMG_9920_A-768x576.jpg 768w, https:\/\/www.ocmflex.com\/wp-content\/uploads\/2025\/11\/IMG_9920_A-1536x1152.jpg 1536w, https:\/\/www.ocmflex.com\/wp-content\/uploads\/2025\/11\/IMG_9920_A-scaled.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-83a7814 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"83a7814\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-040a463\" data-id=\"040a463\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5eca86c elementor-widget elementor-widget-text-editor\" data-id=\"5eca86c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nous vous attendons du 5 au 7 novembre 2025 au <strong>salon Refrigera<\/strong>, pr\u00e9vu \u00e0 BolognaFiere, l&rsquo;\u00e9v\u00e9nement d\u00e9di\u00e9 exclusivement \u00e0 l&rsquo;ensemble de la cha\u00eene de r\u00e9frig\u00e9ration industrielle, commerciale et logistique du sud de l&rsquo;Europe.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-80edaa2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"80edaa2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2d63821\" data-id=\"2d63821\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a56822 elementor-widget elementor-widget-text-editor\" data-id=\"7a56822\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Venez nous rendre visite pour d\u00e9couvrir les solutions les plus avanc\u00e9es en mati\u00e8re de fermetures industrielles &#8211; <strong>Hall 30, Stand A35<\/strong><\/p><p><br>\ud83d\udd39 <strong>Innovation, s\u00e9curit\u00e9 et performance<\/strong>: nos portes rapides \u00e0 fermeture \u00e9clair, en poly\u00e9thyl\u00e8ne et flexibles, sont con\u00e7ues pour r\u00e9pondre aux besoins du secteur de la r\u00e9frig\u00e9ration et de la logistique \u00e0 temp\u00e9rature contr\u00f4l\u00e9e.<\/p><p><br><strong>\ud83d\udd39 Conseils personnalis\u00e9s<\/strong>: notre \u00e9quipe se tient \u00e0 votre disposition pour vous pr\u00e9senter en direct les performances de nos solutions et vous aider \u00e0 trouver celle qui convient le mieux \u00e0 votre installation.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-934eed2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"934eed2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0030123\" data-id=\"0030123\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-93527bb elementor-widget elementor-widget-heading\" data-id=\"93527bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Solutions OCM pour le secteur alimentaire<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-824efa2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"824efa2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3cc478c\" data-id=\"3cc478c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1d8ad29 elementor-widget elementor-widget-text-editor\" data-id=\"1d8ad29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dans le secteur alimentaire, o\u00f9 l&rsquo;hygi\u00e8ne et la s\u00e9curit\u00e9 sont indispensables, nos portes \u00e0 <strong>structure en acier INOX <\/strong>constituent le choix id\u00e9al pour s\u00e9parer les environnements de production, les chambres froides et les zones de conditionnement.<br>OCM Portes Industrielles fabrique sur mesure des portes rapides \u00e0 enroulement zip, des portes flexibles et des portes en poly\u00e9thyl\u00e8ne: ces solutions garantissent <strong>hygi\u00e8ne<\/strong>, <strong>s\u00e9curit\u00e9<\/strong>, <strong>isolation thermique<\/strong> et r\u00e9sistance aux lavages intensifs, r\u00e9pondant ainsi aux normes et aux exigences op\u00e9rationnelles du secteur.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1ca6787 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1ca6787\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d72431f\" data-id=\"d72431f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b45e24d elementor-widget elementor-widget-text-editor\" data-id=\"b45e24d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\ud83d\udccd Ne manquez pas cet \u00e9v\u00e9nement! Refrigera est l&rsquo;occasion id\u00e9ale pour d\u00e9couvrir la <strong>qualit\u00e9 OCM<\/strong> et comment nous pouvons am\u00e9liorer l&rsquo;efficacit\u00e9 et la s\u00e9curit\u00e9 de votre environnement industriel. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3bf14fa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3bf14fa\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e00e570\" data-id=\"e00e570\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f644b09 elementor-widget elementor-widget-text-editor\" data-id=\"f644b09\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>D\u00e9couvrez la gamme compl\u00e8te sur www.ocmflex.com<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-32954f8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"32954f8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bd5d67c\" data-id=\"bd5d67c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5379ecd elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"5379ecd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">+39.01858408301<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-whatsapp\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">+39.0158408301<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-mail-bulk\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">info@ocmflex.com<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Le salon Refrigera 2025 est l&rsquo;occasion id\u00e9ale pour d\u00e9couvrir la qualit\u00e9 OCM et comment nous pouvons am\u00e9liorer l&rsquo;efficacit\u00e9 et la s\u00e9curit\u00e9 de votre environnement industriel.<\/p>\n","protected":false},"author":5,"featured_media":24920,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[106],"tags":[],"class_list":["post-24952","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles"],"_links":{"self":[{"href":"https:\/\/www.ocmflex.com\/fr\/wp-json\/wp\/v2\/posts\/24952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ocmflex.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ocmflex.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ocmflex.com\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ocmflex.com\/fr\/wp-json\/wp\/v2\/comments?post=24952"}],"version-history":[{"count":1,"href":"https:\/\/www.ocmflex.com\/fr\/wp-json\/wp\/v2\/posts\/24952\/revisions"}],"predecessor-version":[{"id":24953,"href":"https:\/\/www.ocmflex.com\/fr\/wp-json\/wp\/v2\/posts\/24952\/revisions\/24953"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ocmflex.com\/fr\/wp-json\/wp\/v2\/media\/24920"}],"wp:attachment":[{"href":"https:\/\/www.ocmflex.com\/fr\/wp-json\/wp\/v2\/media?parent=24952"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ocmflex.com\/fr\/wp-json\/wp\/v2\/categories?post=24952"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ocmflex.com\/fr\/wp-json\/wp\/v2\/tags?post=24952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}